{"id":3305,"date":"2024-02-24T15:08:04","date_gmt":"2024-02-24T15:08:04","guid":{"rendered":"https:\/\/crystalitg.com\/?page_id=3305"},"modified":"2024-02-26T13:54:32","modified_gmt":"2024-02-26T13:54:32","slug":"charcoal","status":"publish","type":"page","link":"https:\/\/crystalitg.com\/it\/charcoal\/","title":{"rendered":"Carbonella"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3305\" class=\"elementor elementor-3305\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f78594 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f78594\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03ef803\" data-id=\"03ef803\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c691ea elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"0c691ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;double_underline&quot;,&quot;highlighted_text&quot;:&quot;on mixed trucks&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Load your charcoal<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">on mixed trucks<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">with pellet, firewood and briquettes too!<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8305a30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8305a30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52f0506\" data-id=\"52f0506\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28a85e6 elementor-widget elementor-widget-text-editor\" data-id=\"28a85e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">With instant products and African very hard wood production, we take to market a great portfolio of charcoal products for both retail and Ho.Re.Ca. markets.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8d8319 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8d8319\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f2a038\" data-id=\"1f2a038\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d11b9b elementor-widget elementor-widget-heading\" data-id=\"2d11b9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">INSTANT BARBECUE <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e0dac4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e0dac4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a572418\" data-id=\"a572418\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-463fb2e elementor-widget elementor-widget-image\" data-id=\"463fb2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"976\" height=\"608\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?fit=976%2C608&ssl=1\" class=\"attachment-large size-large wp-image-3527\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?w=976&ssl=1 976w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?resize=300%2C187&ssl=1 300w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?resize=768%2C478&ssl=1 768w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?resize=570%2C355&ssl=1 570w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?resize=380%2C237&ssl=1 380w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.13.46.png?resize=296%2C184&ssl=1 296w\" sizes=\"(max-width: 976px) 100vw, 976px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-393c9ba\" data-id=\"393c9ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8025018 elementor-widget elementor-widget-text-editor\" data-id=\"8025018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span lang=\"IT\">Description<\/span><\/strong><span lang=\"IT\">:\u00a0<\/span><span style=\"font-size: 20px; text-align: center; font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); color: var(--thm-text);\">Fully FSC certified, this charcoal is from an African tree species which burns longer than any charcoal produced in Europe.<\/span><\/p><p><span style=\"font-size: 20px; text-align: center;\">Instant charcoal is soaked in paraffin and ignites very easily, quickly and in uniform way.<\/span><\/p><p><span style=\"font-size: 20px; text-align: center;\">These are the determining factors for consumer comfort which has taken this product to become the market leader in U.K.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6efe39b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6efe39b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6a1e9a\" data-id=\"a6a1e9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-804405c elementor-widget elementor-widget-heading\" data-id=\"804405c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">INSTANT CHARCOAL<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83efb38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83efb38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b43af9c\" data-id=\"b43af9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a879066 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a879066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 20px; font-weight: bolder; color: var(--thm-black);\"><span lang=\"IT\" style=\"font-size: 20px;\">Description<\/span><\/span><span lang=\"IT\" style=\"font-size: 20px;\">: <\/span>Fully certified FSC, this innovative charcoal is soaked in wax\u00a0 and is compliant with all regulations BSI EN 1860.<\/p><ul><li>2\u00d71 kg Instant charcoal in one package.<\/li><li>Light it with one match without any fuel nor starter.<\/li><li>Clean, fast and convenient solution.<\/li><li>Burns up to 2 hours.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90d041f\" data-id=\"90d041f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb50404 elementor-widget elementor-widget-image\" data-id=\"fb50404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"734\" height=\"500\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?fit=734%2C500&ssl=1\" class=\"attachment-large size-large wp-image-3535\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?w=734&ssl=1 734w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?resize=300%2C204&ssl=1 300w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?resize=570%2C388&ssl=1 570w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?resize=380%2C259&ssl=1 380w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.30.28.png?resize=296%2C202&ssl=1 296w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e56cff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e56cff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30dd5be\" data-id=\"30dd5be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25cfe8d elementor-widget elementor-widget-heading\" data-id=\"25cfe8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">PREMIUM CHARCOAL<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e78b3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e78b3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4328bf\" data-id=\"e4328bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ec043a elementor-widget elementor-widget-text-editor\" data-id=\"0ec043a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Description<\/strong>: Premium charcoal certified FSC and BS EN 1860, Number 1 for sales in the U.K., it is ready to cook in 20 minutes.<\/p><p>This premium FSC certified charcoal burns evenly for 1.5 hours (very hard African Acacia wood).<\/p><p>It can be supplied in Standard grain size (Lumpwood) and increased grain size (Restaurant quality).<b><\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01fa27a\" data-id=\"01fa27a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b239970 elementor-widget elementor-widget-image\" data-id=\"b239970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"446\" height=\"424\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.43.01.png?fit=446%2C424&ssl=1\" class=\"attachment-large size-large wp-image-3545\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.43.01.png?w=446&ssl=1 446w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.43.01.png?resize=300%2C285&ssl=1 300w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.43.01.png?resize=380%2C361&ssl=1 380w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.43.01.png?resize=296%2C281&ssl=1 296w\" sizes=\"(max-width: 446px) 100vw, 446px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2250244 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2250244\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e79b278\" data-id=\"e79b278\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac080c7 elementor-widget elementor-widget-image\" data-id=\"ac080c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"216\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?fit=940%2C216&ssl=1\" class=\"attachment-large size-large wp-image-3546\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?w=940&ssl=1 940w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?resize=300%2C69&ssl=1 300w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?resize=768%2C176&ssl=1 768w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?resize=570%2C131&ssl=1 570w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?resize=380%2C87&ssl=1 380w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-25-at-19.18.15.png?resize=296%2C68&ssl=1 296w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fded85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fded85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6272e61\" data-id=\"6272e61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1cf3f8 elementor-widget elementor-widget-heading\" data-id=\"f1cf3f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">TESTIMONIALS<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f31c63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f31c63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fa45c6\" data-id=\"4fa45c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cef4de0 elementor-widget elementor-widget-linoor-testimonials\" data-id=\"cef4de0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"linoor-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<section class=\"testimonials-seven\">\r\n\t\t<div class=\"auto-container\">\r\n\t\t\t\t\t\t<div class=\"testimonials-seven__nav\">\r\n\t\t\t\t<div id=\"testimonials-seven__swiper-button-next\">\r\n\t\t\t\t\t<span class=\"flaticon-left-arrow-2\"><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div id=\"testimonials-seven__swiper-button-prev\">\r\n\t\t\t\t\t<span class=\"flaticon-send\"><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div><!-- \/.auto-container -->\r\n\t\t<div class=\"testimonials-seven__slider-wrapper\">\r\n\t\t\t<div class=\"testimonials-seven__slider\">\r\n\r\n\t\t\t\t<div class=\"thm-swiper__slider swiper-container\" data-swiper-options='{\"spaceBetween\": 30, \"loop\": true, \"slidesPerGroup\": 3,  \"autoplay\": { \"delay\": 5000 }, \"navigation\": { \"nextEl\": \"#testimonials-seven__swiper-button-next\", \"prevEl\": \"#testimonials-seven__swiper-button-prev\" }, \"breakpoints\": {\r\n\t\t\t\t\"0\": {\r\n\t\t\t\t\t\"spaceBetween\": 0,\r\n\t\t\t\t\t\"slidesPerView\": 1\r\n\t\t\t\t},\r\n\t\t\t\t\"375\": {\r\n\t\t\t\t\t\"spaceBetween\": 0,\r\n\t\t\t\t\t\"slidesPerView\": 1\r\n\t\t\t\t},\r\n\t\t\t\t\"767\": {\r\n\t\t\t\t\t\"spaceBetween\": 30,\r\n\t\t\t\t\t\"slidesPerView\": 2\r\n\t\t\t\t},\r\n\t\t\t\t\"991\": {\r\n\t\t\t\t\t\"spaceBetween\": 30,\r\n\t\t\t\t\t\"slidesPerView\": 3\r\n\t\t\t\t},\r\n\t\t\t\t\"1199\": {\r\n\t\t\t\t\t\"spaceBetween\": 30,\r\n\t\t\t\t\t\"slidesPerView\": 3\r\n\t\t\t\t}\r\n\t\t\t}}'>\r\n\t\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__item\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__top\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"77\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=77%2C77&ssl=1\" class=\"attachment-linoor_testimonials_77X77 size-linoor_testimonials_77X77 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=286%2C290&ssl=1 286w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=73%2C73&ssl=1 73w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=77%2C77&ssl=1 77w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=63%2C63&ssl=1 63w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=125%2C125&ssl=1 125w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=192%2C192&ssl=1 192w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=270%2C270&ssl=1 270w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/Vidmants.jpg?resize=100%2C100&ssl=1 100w\" sizes=\"(max-width: 77px) 100vw, 77px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__image -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__info\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"testimonials-seven__name\">Vidmants<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__name -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"testimonials-seven__designation\"><\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__designation -->\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__info -->\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__top -->\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__content\">For my home I want only the best: crystal has it and delivers when they promise. 5 stars service: 100% suggested<\/div><!-- \/.testimonials-seven__content -->\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__item -->\r\n\t\t\t\t\t\t\t\t<\/div><!-- \/.swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__item\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__top\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"77\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=77%2C77&ssl=1\" class=\"attachment-linoor_testimonials_77X77 size-linoor_testimonials_77X77 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=73%2C73&ssl=1 73w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=77%2C77&ssl=1 77w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=63%2C63&ssl=1 63w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=125%2C125&ssl=1 125w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=192%2C192&ssl=1 192w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=270%2C270&ssl=1 270w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2022\/04\/IMG_1520.jpg?resize=100%2C100&ssl=1 100w\" sizes=\"(max-width: 77px) 100vw, 77px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__image -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__info\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"testimonials-seven__name\">Natalija<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__name -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"testimonials-seven__designation\"><\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__designation -->\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__info -->\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__top -->\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__content\">Since when I started to use Crystal pellet I did not call the technician for 2 years: no ash, super power. The best pellet in the market for sure!<\/div><!-- \/.testimonials-seven__content -->\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__item -->\r\n\t\t\t\t\t\t\t\t<\/div><!-- \/.swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__item\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__top\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"77\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=77%2C77&ssl=1\" class=\"attachment-linoor_testimonials_77X77 size-linoor_testimonials_77X77 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=73%2C73&ssl=1 73w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=77%2C77&ssl=1 77w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=63%2C63&ssl=1 63w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=125%2C125&ssl=1 125w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=192%2C192&ssl=1 192w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=270%2C270&ssl=1 270w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1515.jpg?resize=100%2C100&ssl=1 100w\" sizes=\"(max-width: 77px) 100vw, 77px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__image -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__info\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"testimonials-seven__name\">Linda<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__name -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"testimonials-seven__designation\"><\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__designation -->\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__info -->\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__top -->\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__content\">Since when I passed from not certified (but cheaper) pellet I spent more to buy, but I saved so much money in technical cleaning and reparations during all year long: and no mo stop to the heating: I run a school and a kindergarten, now my little customers are 100% warm all winter long.<\/div><!-- \/.testimonials-seven__content -->\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__item -->\r\n\t\t\t\t\t\t\t\t<\/div><!-- \/.swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__item\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__top\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"77\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=77%2C77&ssl=1\" class=\"attachment-linoor_testimonials_77X77 size-linoor_testimonials_77X77 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=73%2C73&ssl=1 73w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=77%2C77&ssl=1 77w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=63%2C63&ssl=1 63w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=125%2C125&ssl=1 125w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=192%2C192&ssl=1 192w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=270%2C270&ssl=1 270w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1531.jpg?resize=100%2C100&ssl=1 100w\" sizes=\"(max-width: 77px) 100vw, 77px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__image -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__info\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"testimonials-seven__name\">Jurijs<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__name -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"testimonials-seven__designation\"><\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__designation -->\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__info -->\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__top -->\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__content\">Fast delivery, cool packaging, hot home: what else? Ah, yes, it is produced in Latvia!<\/div><!-- \/.testimonials-seven__content -->\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__item -->\r\n\t\t\t\t\t\t\t\t<\/div><!-- \/.swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__item\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__top\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"77\" src=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=77%2C77&ssl=1\" class=\"attachment-linoor_testimonials_77X77 size-linoor_testimonials_77X77 wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?w=2560&ssl=1 2560w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=300%2C295&ssl=1 300w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=1024%2C1006&ssl=1 1024w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=768%2C754&ssl=1 768w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=1536%2C1509&ssl=1 1536w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=2048%2C2011&ssl=1 2048w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=73%2C73&ssl=1 73w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=77%2C77&ssl=1 77w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=63%2C63&ssl=1 63w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=125%2C125&ssl=1 125w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=192%2C192&ssl=1 192w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=270%2C270&ssl=1 270w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=570%2C560&ssl=1 570w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=380%2C373&ssl=1 380w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=296%2C291&ssl=1 296w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=1320%2C1296&ssl=1 1320w, https:\/\/i0.wp.com\/crystalitg.com\/wp-content\/uploads\/2021\/01\/IMG_1509-scaled.jpg?resize=100%2C100&ssl=1 100w\" sizes=\"(max-width: 77px) 100vw, 77px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__image -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__info\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"testimonials-seven__name\">Andris<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__name -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"testimonials-seven__designation\"><\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<!-- \/.testimonials-seven__designation -->\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__info -->\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__top -->\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"testimonials-seven__content\">Crystal delivered simply the best pellet I have ever seen: clean stove, high calorific power, perfect packaging to be stored in the garden. and fast delivery to my home too!<\/div><!-- \/.testimonials-seven__content -->\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- \/.testimonials-seven__item -->\r\n\t\t\t\t\t\t\t\t<\/div><!-- \/.swiper-slide -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t<\/div><!-- \/.testimonials-seven__slider -->\r\n\t\t<\/div><!-- \/.testimonials-seven__slider-wrapper -->\r\n\t<\/section><!-- \/.testimonials-seven -->\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9b3fda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9b3fda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d22a8e\" data-id=\"0d22a8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88d8ac2 elementor-widget elementor-widget-spacer\" data-id=\"88d8ac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9e27fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9e27fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b271a1c\" data-id=\"b271a1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597b13f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"597b13f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>WRITE US YOUR REQUEST<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08d46ae\" data-id=\"08d46ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0940099 elementor-widget elementor-widget-text-editor\" data-id=\"0940099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>CALL OUR SALES DEPARTMENT<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91cbee5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91cbee5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ef5021\" data-id=\"3ef5021\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a345c5 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"9a345c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"3305\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"9a345c5\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-md\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-align-icon-left elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" flaticon-email\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SEND EMAIL<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44aef9d\" data-id=\"44aef9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba31df elementor-align-center elementor-absolute elementor-widget elementor-widget-button\" data-id=\"5ba31df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\" flaticon-telephone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PHONE: +371 20268107<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42a6c9f elementor-section-full_width main-footer elementor-section-height-default elementor-section-height-default\" data-id=\"42a6c9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11884f6\" data-id=\"11884f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2badc0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2badc0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-12feb45\" data-id=\"12feb45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b27b4c elementor-widget elementor-widget-footer-nav-menu\" data-id=\"5b27b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"footer-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"footer-widget links-widget\">\r\n        <div class=\"widget-content\">\r\n            <h6>Explore<\/h6>\r\n            <div class=\"row clearfix\">\r\n                                    <div class=\"col-md-6 col-sm-12\">\r\n                        <div class=\"menu-footer-menu-2-container\"><ul id=\"menu-footer-menu-2\" class=\"list-unstyled m-0\"><li id=\"menu-item-2268\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2268\"><a href=\"https:\/\/crystalitg.com\/it\/contact-us\/\">Contact Us<\/a><\/li>\n<li id=\"menu-item-2932\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2932\"><a href=\"https:\/\/crystalitg.com\/it\/privacy\/\">Privacy<\/a><\/li>\n<li id=\"menu-item-2943\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2943\"><a href=\"https:\/\/crystalitg.com\/it\/ordersreturns\/\">Orders & Returns<\/a><\/li>\n<li id=\"menu-item-3126\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3126\"><a href=\"https:\/\/crystalitg.com\/it\/terms-of-use-2\/\">Terms of Use<\/a><\/li>\n<\/ul><\/div>                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dbe2b32\" data-id=\"dbe2b32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-314c376 elementor-widget elementor-widget-footer-contact\" data-id=\"314c376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"footer-contact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"footer-widget info-widget\">\r\n        <div class=\"widget-content\">\r\n            <h6>Contact<\/h6>\r\n            <ul class=\"contact-info m-0 list-unstyled\">\r\n                                    <li class=\"address\">\r\n                                                <span class=\"icon flaticon-pin-1 \"><\/span>\r\n                        Jana Asara iela 12, LV-3001 Jelgava LATVIA                    <\/li>\r\n                                    <li class=\"address\">\r\n                                                <span class=\"icon  \"><\/span>\r\n                        Reg. nr. 43603043365                     <\/li>\r\n                                    <li class=\"address\">\r\n                                                <span class=\"icon flaticon-call \"><\/span>\r\n                        <a href=\"0037120268107\">00371 20268107<\/a>                    <\/li>\r\n                                    <li class=\"address\">\r\n                                                <span class=\"icon flaticon-email-2 \"><\/span>\r\n                        <a href=\"mailto:needhelp@linoor.com\">admin@crystalitg.com<\/a>                    <\/li>\r\n                            <\/ul>\r\n        <\/div>\r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5523577\" data-id=\"5523577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ba721d elementor-widget elementor-widget-footer-subscribe\" data-id=\"8ba721d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"footer-subscribe.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"footer-widget newsletter-widget\">\r\n        <div class=\"widget-content\">\r\n            <h6>Newsletter<\/h6>\r\n            <div class=\"newsletter-form\">\r\n                <form class=\"mc-form\" data-url=\"#\">\r\n                    <div class=\"form-group clearfix\">\r\n                        <input type=\"email\" name=\"EMAIL\" value=\"\" placeholder=\"Email Address\">\r\n                        <button type=\"submit\" class=\"theme-btn\"><span class=\"fa fa-envelope\"><\/span><\/button>\r\n                    <\/div>\r\n                <\/form>\r\n                <div class=\"mc-form__response\"><\/div>\r\n            <\/div>\r\n            <div class=\"text\">Sign up for discounts and special offers: no spam guaranteed!<\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ef8cd86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef8cd86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7ab9863\" data-id=\"7ab9863\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff235ed elementor-widget elementor-widget-footer-copyright\" data-id=\"ff235ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"footer-copyright.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"footer-bottom\">\r\n    <div class=\"auto-container\">\r\n        <div class=\"inner clearfix\">\r\n            <div class=\"copyright\">\u00a9 copyright 2011-2022 by \"Crystal ITG\" SIA<\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Load your charcoal on mixed trucks with pellet, firewood and briquettes too! With instant products and African very hard wood production, we take to market a great portfolio of charcoal products for both retail and Ho.Re.Ca. markets. INSTANT BARBECUE Description:\u00a0Fully FSC certified, this charcoal is from an African tree species which burns longer than any [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2254,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3305","page","type-page","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/pages\/3305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/comments?post=3305"}],"version-history":[{"count":25,"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/pages\/3305\/revisions"}],"predecessor-version":[{"id":3635,"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/pages\/3305\/revisions\/3635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/media\/2254"}],"wp:attachment":[{"href":"https:\/\/crystalitg.com\/it\/wp-json\/wp\/v2\/media?parent=3305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}